{"id":28670,"date":"2025-03-19T16:43:25","date_gmt":"2025-03-19T15:43:25","guid":{"rendered":"https:\/\/circulojpes.com\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/"},"modified":"2025-12-22T12:45:51","modified_gmt":"2025-12-22T11:45:51","slug":"%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3","status":"publish","type":"post","link":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/","title":{"rendered":"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":27977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-28670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-empresas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059 - CEJE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/circulojpes.com\/ja\/\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08ceje\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059 - CEJE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/circulojpes.com\/ja\/\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08ceje\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\/\" \/>\n<meta property=\"og:site_name\" content=\"CEJE\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T15:43:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T11:45:51+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#\\\/schema\\\/person\\\/8cb712462983d286a0ccef34c4ddcd32\"},\"headline\":\"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059\",\"datePublished\":\"2025-03-19T15:43:25+00:00\",\"dateModified\":\"2025-12-22T11:45:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Noticias de Socios\"],\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/\",\"url\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/\",\"name\":\"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059 - CEJE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2025-03-19T15:43:25+00:00\",\"dateModified\":\"2025-12-22T11:45:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/circulojpes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#website\",\"url\":\"https:\\\/\\\/circulojpes.com\\\/\",\"name\":\"CEJE\",\"description\":\"Circulo Empresarial Jap\u00f3n Espa\u00f1a\",\"publisher\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/circulojpes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#organization\",\"name\":\"Circulo Empresarial Jap\u00f3n Espa\u00f1a\",\"url\":\"https:\\\/\\\/circulojpes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/circulojpes.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-logo-ceje.png\",\"contentUrl\":\"https:\\\/\\\/circulojpes.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cropped-logo-ceje.png\",\"width\":830,\"height\":364,\"caption\":\"Circulo Empresarial Jap\u00f3n Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/circulojpes.com\\\/#\\\/schema\\\/person\\\/8cb712462983d286a0ccef34c4ddcd32\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f8a80423e78c72c6bcbdd138d171d75dc6fd775c651ab3646a832b24e808ed0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f8a80423e78c72c6bcbdd138d171d75dc6fd775c651ab3646a832b24e808ed0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f8a80423e78c72c6bcbdd138d171d75dc6fd775c651ab3646a832b24e808ed0?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/circulojpes.com\"],\"url\":\"https:\\\/\\\/circulojpes.com\\\/ja\\\/author\\\/ceje_2025\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059 - CEJE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/circulojpes.com\/ja\/\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08ceje\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\/","og_locale":"ja_JP","og_type":"article","og_title":"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059 - CEJE","og_url":"https:\/\/circulojpes.com\/ja\/\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08ceje\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\/","og_site_name":"CEJE","article_published_time":"2025-03-19T15:43:25+00:00","article_modified_time":"2025-12-22T11:45:51+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#article","isPartOf":{"@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/"},"author":{"name":"admin","@id":"https:\/\/circulojpes.com\/#\/schema\/person\/8cb712462983d286a0ccef34c4ddcd32"},"headline":"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059","datePublished":"2025-03-19T15:43:25+00:00","dateModified":"2025-12-22T11:45:51+00:00","mainEntityOfPage":{"@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/circulojpes.com\/#organization"},"image":{"@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#primaryimage"},"thumbnailUrl":"","articleSection":["Noticias de Socios"],"inLanguage":"ja","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/","url":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/","name":"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059 - CEJE","isPartOf":{"@id":"https:\/\/circulojpes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#primaryimage"},"image":{"@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#primaryimage"},"thumbnailUrl":"","datePublished":"2025-03-19T15:43:25+00:00","dateModified":"2025-12-22T11:45:51+00:00","breadcrumb":{"@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/circulojpes.com\/ja\/%e6%97%a5%e6%9c%ac%e3%83%bb%e3%82%b9%e3%83%9a%e3%82%a4%e3%83%b3%e4%bc%81%e6%a5%ad%e3%82%b5%e3%83%bc%e3%82%af%e3%83%ab%ef%bc%88ceje%ef%bc%89%e3%80%81%e3%83%9b%e3%82%a2%e3%83%b3%e3%83%bb%e3%82%b3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/circulojpes.com\/"},{"@type":"ListItem","position":2,"name":"\u65e5\u672c\u30fb\u30b9\u30da\u30a4\u30f3\u4f01\u696d\u30b5\u30fc\u30af\u30eb\uff08CEJE\uff09\u3001\u30db\u30a2\u30f3\u30fb\u30b3\u30ed\u30df\u30cd\u30b9\u6c0f\u306b\u6df1\u3044\u54c0\u60bc\u306e\u610f\u3092\u793a\u3059"}]},{"@type":"WebSite","@id":"https:\/\/circulojpes.com\/#website","url":"https:\/\/circulojpes.com\/","name":"CEJE","description":"Circulo Empresarial Jap\u00f3n Espa\u00f1a","publisher":{"@id":"https:\/\/circulojpes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/circulojpes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/circulojpes.com\/#organization","name":"Circulo Empresarial Jap\u00f3n Espa\u00f1a","url":"https:\/\/circulojpes.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/circulojpes.com\/#\/schema\/logo\/image\/","url":"https:\/\/circulojpes.com\/wp-content\/uploads\/2025\/10\/cropped-logo-ceje.png","contentUrl":"https:\/\/circulojpes.com\/wp-content\/uploads\/2025\/10\/cropped-logo-ceje.png","width":830,"height":364,"caption":"Circulo Empresarial Jap\u00f3n Espa\u00f1a"},"image":{"@id":"https:\/\/circulojpes.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/circulojpes.com\/#\/schema\/person\/8cb712462983d286a0ccef34c4ddcd32","name":"admin","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/secure.gravatar.com\/avatar\/3f8a80423e78c72c6bcbdd138d171d75dc6fd775c651ab3646a832b24e808ed0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3f8a80423e78c72c6bcbdd138d171d75dc6fd775c651ab3646a832b24e808ed0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f8a80423e78c72c6bcbdd138d171d75dc6fd775c651ab3646a832b24e808ed0?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/circulojpes.com"],"url":"https:\/\/circulojpes.com\/ja\/author\/ceje_2025\/"}]}},"_links":{"self":[{"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/posts\/28670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/comments?post=28670"}],"version-history":[{"count":1,"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/posts\/28670\/revisions"}],"predecessor-version":[{"id":30249,"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/posts\/28670\/revisions\/30249"}],"wp:attachment":[{"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/media?parent=28670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/categories?post=28670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/circulojpes.com\/ja\/wp-json\/wp\/v2\/tags?post=28670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}